{"id":7,"count":4,"description":"","link":"https:\/\/demostracionweb.com\/centolo\/category\/creative\/food\/","name":"Food","slug":"food","taxonomy":"category","parent":3,"meta":[],"_links":{"self":[{"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/categories\/7"}],"collection":[{"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/categories\/3"}],"wp:post_type":[{"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}