{"id":2331,"date":"2016-04-21T11:26:17","date_gmt":"2016-04-21T11:26:17","guid":{"rendered":"http:\/\/savory.elated-themes.com\/?page_id=2331"},"modified":"2016-04-21T11:26:17","modified_gmt":"2016-04-21T11:26:17","slug":"standard-four-columns-wide","status":"publish","type":"page","link":"https:\/\/demostracionweb.com\/centolo\/portfolio\/standard-four-columns-wide\/","title":{"rendered":"Standard Four Columns Wide"},"content":{"rendered":"<p>[vc_row][vc_column]<div class = \"eltd-portfolio-list-wrapper clearfix\"><div class = \"eltd-portfolio-list-holder-outer eltd-ptf-standard eltd-ptf-large-spacing eltd-ptf-four-columns eltd-no-appear-effect\" data-next-page= \"2\" data-type= \"standard\" data-columns= \"four\" data-grid-size= \"three\" data-order-by= \"date\" data-order= \"DESC\" data-number= \"12\" data-image-size= \"landscape\" data-filter= \"no\" data-filter-order-by= \"name\" data-category= \"restaurant\" data-enable-pagination= \"no\" data-title-tag= \"h4\" data-max-num-pages = 2><div class = \"eltd-portfolio-list-holder clearfix\" ><article class=\"eltd-portfolio-item mix portfolio_category_72\">\n\n\t\n\t\t<div class = \"eltd-item-image-holder\" >\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/italian-fast-food\/\">\n\t\t\t\t<img width=\"800\" height=\"545\" src=\"https:\/\/demostracionweb.com\/centolo\/wp-content\/uploads\/2016\/10\/port-fi-15-800x545.jpg\" class=\"attachment-savory_elated_landscape size-savory_elated_landscape wp-post-image\" alt=\"g\" loading=\"lazy\" \/>\t\t\t<\/a>\n\n\t\t<\/div>\n\n\t\n\t<div class=\"eltd-item-text-holder\">\n\n\t\t<h4 class=\"eltd-item-title\">\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/italian-fast-food\/\">\n\t\t\t\tItalian Fast Food\t\t\t<\/a>\n\n\t\t<\/h4>\n\n\t\t\n\t\t\n\t\t\t\t<div class=\"eltd-ptf-category-like-holder clearfix\">\n\t\t\t\t\t<div class=\"eltd-ptf-category-holder\"><a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-category\/fast-food\/\"><span>Fast Food<\/span><\/a><\/div><div class=\"eltd-ptf-like-holder\"><a class=\"eltd-like\" data-type=\"portfolio_list\" id=\"eltd-like-7079-193\" title=\"Like this\"><\/a><\/div>\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n<\/article>\n<article class=\"eltd-portfolio-item mix portfolio_category_72\">\n\n\t\n\t\t<div class = \"eltd-item-image-holder\" >\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/sweet-snacks\/\">\n\t\t\t\t<img width=\"800\" height=\"545\" src=\"https:\/\/demostracionweb.com\/centolo\/wp-content\/uploads\/2016\/10\/port-fi-14-800x545.jpg\" class=\"attachment-savory_elated_landscape size-savory_elated_landscape wp-post-image\" alt=\"g\" loading=\"lazy\" \/>\t\t\t<\/a>\n\n\t\t<\/div>\n\n\t\n\t<div class=\"eltd-item-text-holder\">\n\n\t\t<h4 class=\"eltd-item-title\">\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/sweet-snacks\/\">\n\t\t\t\tSweet Snacks\t\t\t<\/a>\n\n\t\t<\/h4>\n\n\t\t\n\t\t\n\t\t\t\t<div class=\"eltd-ptf-category-like-holder clearfix\">\n\t\t\t\t\t<div class=\"eltd-ptf-category-holder\"><a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-category\/fast-food\/\"><span>Fast Food<\/span><\/a><\/div><div class=\"eltd-ptf-like-holder\"><a class=\"eltd-like\" data-type=\"portfolio_list\" id=\"eltd-like-7064-359\" title=\"Like this\"><\/a><\/div>\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n<\/article>\n<article class=\"eltd-portfolio-item mix portfolio_category_67\">\n\n\t\n\t\t<div class = \"eltd-item-image-holder\" >\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/fast-made-meal\/\">\n\t\t\t\t<img width=\"800\" height=\"545\" src=\"https:\/\/demostracionweb.com\/centolo\/wp-content\/uploads\/2016\/10\/port-fi-13-800x545.jpg\" class=\"attachment-savory_elated_landscape size-savory_elated_landscape wp-post-image\" alt=\"d\" loading=\"lazy\" \/>\t\t\t<\/a>\n\n\t\t<\/div>\n\n\t\n\t<div class=\"eltd-item-text-holder\">\n\n\t\t<h4 class=\"eltd-item-title\">\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/fast-made-meal\/\">\n\t\t\t\tFast Made Meal\t\t\t<\/a>\n\n\t\t<\/h4>\n\n\t\t\n\t\t\n\t\t\t\t<div class=\"eltd-ptf-category-like-holder clearfix\">\n\t\t\t\t\t<div class=\"eltd-ptf-category-holder\"><a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-category\/burger\/\"><span>Burger<\/span><\/a><\/div><div class=\"eltd-ptf-like-holder\"><a class=\"eltd-like\" data-type=\"portfolio_list\" id=\"eltd-like-7065-654\" title=\"Like this\"><\/a><\/div>\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n<\/article>\n<article class=\"eltd-portfolio-item mix portfolio_category_72\">\n\n\t\n\t\t<div class = \"eltd-item-image-holder\" >\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/honey-glazed-chicken\/\">\n\t\t\t\t<img width=\"800\" height=\"545\" src=\"https:\/\/demostracionweb.com\/centolo\/wp-content\/uploads\/2016\/10\/port-fi-12-800x545.jpg\" class=\"attachment-savory_elated_landscape size-savory_elated_landscape wp-post-image\" alt=\"h\" loading=\"lazy\" \/>\t\t\t<\/a>\n\n\t\t<\/div>\n\n\t\n\t<div class=\"eltd-item-text-holder\">\n\n\t\t<h4 class=\"eltd-item-title\">\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/honey-glazed-chicken\/\">\n\t\t\t\tHoney Glazed Chicken\t\t\t<\/a>\n\n\t\t<\/h4>\n\n\t\t\n\t\t\n\t\t\t\t<div class=\"eltd-ptf-category-like-holder clearfix\">\n\t\t\t\t\t<div class=\"eltd-ptf-category-holder\"><a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-category\/fast-food\/\"><span>Fast Food<\/span><\/a><\/div><div class=\"eltd-ptf-like-holder\"><a class=\"eltd-like\" data-type=\"portfolio_list\" id=\"eltd-like-7066-623\" title=\"Like this\"><\/a><\/div>\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n<\/article>\n<article class=\"eltd-portfolio-item mix portfolio_category_70\">\n\n\t\n\t\t<div class = \"eltd-item-image-holder\" >\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/sweets-for-breakfast\/\">\n\t\t\t\t<img width=\"800\" height=\"545\" src=\"https:\/\/demostracionweb.com\/centolo\/wp-content\/uploads\/2016\/10\/port-fi-11-800x545.jpg\" class=\"attachment-savory_elated_landscape size-savory_elated_landscape wp-post-image\" alt=\"d\" loading=\"lazy\" \/>\t\t\t<\/a>\n\n\t\t<\/div>\n\n\t\n\t<div class=\"eltd-item-text-holder\">\n\n\t\t<h4 class=\"eltd-item-title\">\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/sweets-for-breakfast\/\">\n\t\t\t\tSweets For Breakfast\t\t\t<\/a>\n\n\t\t<\/h4>\n\n\t\t\n\t\t\n\t\t\t\t<div class=\"eltd-ptf-category-like-holder clearfix\">\n\t\t\t\t\t<div class=\"eltd-ptf-category-holder\"><a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-category\/dessert\/\"><span>Dessert<\/span><\/a><\/div><div class=\"eltd-ptf-like-holder\"><a class=\"eltd-like\" data-type=\"portfolio_list\" id=\"eltd-like-7067-626\" title=\"Like this\"><\/a><\/div>\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n<\/article>\n<article class=\"eltd-portfolio-item mix portfolio_category_72\">\n\n\t\n\t\t<div class = \"eltd-item-image-holder\" >\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/small-apperizers\/\">\n\t\t\t\t<img width=\"800\" height=\"545\" src=\"https:\/\/demostracionweb.com\/centolo\/wp-content\/uploads\/2016\/10\/port-fi-10-800x545.jpg\" class=\"attachment-savory_elated_landscape size-savory_elated_landscape wp-post-image\" alt=\"S\" loading=\"lazy\" \/>\t\t\t<\/a>\n\n\t\t<\/div>\n\n\t\n\t<div class=\"eltd-item-text-holder\">\n\n\t\t<h4 class=\"eltd-item-title\">\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/small-apperizers\/\">\n\t\t\t\tSmall Apperizers\t\t\t<\/a>\n\n\t\t<\/h4>\n\n\t\t\n\t\t\n\t\t\t\t<div class=\"eltd-ptf-category-like-holder clearfix\">\n\t\t\t\t\t<div class=\"eltd-ptf-category-holder\"><a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-category\/fast-food\/\"><span>Fast Food<\/span><\/a><\/div><div class=\"eltd-ptf-like-holder\"><a class=\"eltd-like\" data-type=\"portfolio_list\" id=\"eltd-like-7068-258\" title=\"Like this\"><\/a><\/div>\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n<\/article>\n<article class=\"eltd-portfolio-item mix portfolio_category_67\">\n\n\t\n\t\t<div class = \"eltd-item-image-holder\" >\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/cheese-in-burger\/\">\n\t\t\t\t<img width=\"800\" height=\"545\" src=\"https:\/\/demostracionweb.com\/centolo\/wp-content\/uploads\/2016\/10\/port-fi-9-800x545.jpg\" class=\"attachment-savory_elated_landscape size-savory_elated_landscape wp-post-image\" alt=\"\" loading=\"lazy\" \/>\t\t\t<\/a>\n\n\t\t<\/div>\n\n\t\n\t<div class=\"eltd-item-text-holder\">\n\n\t\t<h4 class=\"eltd-item-title\">\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/cheese-in-burger\/\">\n\t\t\t\tMushrooms Bites\t\t\t<\/a>\n\n\t\t<\/h4>\n\n\t\t\n\t\t\n\t\t\t\t<div class=\"eltd-ptf-category-like-holder clearfix\">\n\t\t\t\t\t<div class=\"eltd-ptf-category-holder\"><a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-category\/burger\/\"><span>Burger<\/span><\/a><\/div><div class=\"eltd-ptf-like-holder\"><a class=\"eltd-like\" data-type=\"portfolio_list\" id=\"eltd-like-7069-713\" title=\"Like this\"><\/a><\/div>\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n<\/article>\n<article class=\"eltd-portfolio-item mix portfolio_category_67\">\n\n\t\n\t\t<div class = \"eltd-item-image-holder\" >\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/make-ice-cream\/\">\n\t\t\t\t<img width=\"800\" height=\"545\" src=\"https:\/\/demostracionweb.com\/centolo\/wp-content\/uploads\/2016\/10\/port-fi-8-800x545.jpg\" class=\"attachment-savory_elated_landscape size-savory_elated_landscape wp-post-image\" alt=\"\" loading=\"lazy\" \/>\t\t\t<\/a>\n\n\t\t<\/div>\n\n\t\n\t<div class=\"eltd-item-text-holder\">\n\n\t\t<h4 class=\"eltd-item-title\">\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/make-ice-cream\/\">\n\t\t\t\tDifferent Taste\t\t\t<\/a>\n\n\t\t<\/h4>\n\n\t\t\n\t\t\n\t\t\t\t<div class=\"eltd-ptf-category-like-holder clearfix\">\n\t\t\t\t\t<div class=\"eltd-ptf-category-holder\"><a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-category\/burger\/\"><span>Burger<\/span><\/a><\/div><div class=\"eltd-ptf-like-holder\"><a class=\"eltd-like\" data-type=\"portfolio_list\" id=\"eltd-like-7070-845\" title=\"Like this\"><\/a><\/div>\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n<\/article>\n<article class=\"eltd-portfolio-item mix portfolio_category_72\">\n\n\t\n\t\t<div class = \"eltd-item-image-holder\" >\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/food-hedonist\/\">\n\t\t\t\t<img width=\"800\" height=\"545\" src=\"https:\/\/demostracionweb.com\/centolo\/wp-content\/uploads\/2016\/10\/port-fi-7-800x545.jpg\" class=\"attachment-savory_elated_landscape size-savory_elated_landscape wp-post-image\" alt=\"d\" loading=\"lazy\" \/>\t\t\t<\/a>\n\n\t\t<\/div>\n\n\t\n\t<div class=\"eltd-item-text-holder\">\n\n\t\t<h4 class=\"eltd-item-title\">\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/food-hedonist\/\">\n\t\t\t\tFood Hedonist\t\t\t<\/a>\n\n\t\t<\/h4>\n\n\t\t\n\t\t\n\t\t\t\t<div class=\"eltd-ptf-category-like-holder clearfix\">\n\t\t\t\t\t<div class=\"eltd-ptf-category-holder\"><a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-category\/fast-food\/\"><span>Fast Food<\/span><\/a><\/div><div class=\"eltd-ptf-like-holder\"><a class=\"eltd-like\" data-type=\"portfolio_list\" id=\"eltd-like-7044-131\" title=\"Like this\"><\/a><\/div>\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n<\/article>\n<article class=\"eltd-portfolio-item mix portfolio_category_67\">\n\n\t\n\t\t<div class = \"eltd-item-image-holder\" >\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/easy-recipes\/\">\n\t\t\t\t<img width=\"500\" height=\"500\" src=\"https:\/\/demostracionweb.com\/centolo\/wp-content\/uploads\/2021\/06\/josh-woodward-gravity-mp3-image.jpg\" class=\"attachment-savory_elated_landscape size-savory_elated_landscape wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demostracionweb.com\/centolo\/wp-content\/uploads\/2021\/06\/josh-woodward-gravity-mp3-image.jpg 500w, https:\/\/demostracionweb.com\/centolo\/wp-content\/uploads\/2021\/06\/josh-woodward-gravity-mp3-image-300x300.jpg 300w, https:\/\/demostracionweb.com\/centolo\/wp-content\/uploads\/2021\/06\/josh-woodward-gravity-mp3-image-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t<\/a>\n\n\t\t<\/div>\n\n\t\n\t<div class=\"eltd-item-text-holder\">\n\n\t\t<h4 class=\"eltd-item-title\">\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/easy-recipes\/\">\n\t\t\t\tEasy Recipes\t\t\t<\/a>\n\n\t\t<\/h4>\n\n\t\t\n\t\t\n\t\t\t\t<div class=\"eltd-ptf-category-like-holder clearfix\">\n\t\t\t\t\t<div class=\"eltd-ptf-category-holder\"><a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-category\/burger\/\"><span>Burger<\/span><\/a><\/div><div class=\"eltd-ptf-like-holder\"><a class=\"eltd-like\" data-type=\"portfolio_list\" id=\"eltd-like-629-174\" title=\"Like this\"><\/a><\/div>\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n<\/article>\n<article class=\"eltd-portfolio-item mix portfolio_category_72\">\n\n\t\n\t\t<div class = \"eltd-item-image-holder\" >\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/favorite-burger\/\">\n\t\t\t\t<img width=\"800\" height=\"545\" src=\"https:\/\/demostracionweb.com\/centolo\/wp-content\/uploads\/2016\/04\/port-fi-6-800x545.jpg\" class=\"attachment-savory_elated_landscape size-savory_elated_landscape wp-post-image\" alt=\"g\" loading=\"lazy\" \/>\t\t\t<\/a>\n\n\t\t<\/div>\n\n\t\n\t<div class=\"eltd-item-text-holder\">\n\n\t\t<h4 class=\"eltd-item-title\">\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/favorite-burger\/\">\n\t\t\t\tFavorite Burger\t\t\t<\/a>\n\n\t\t<\/h4>\n\n\t\t\n\t\t\n\t\t\t\t<div class=\"eltd-ptf-category-like-holder clearfix\">\n\t\t\t\t\t<div class=\"eltd-ptf-category-holder\"><a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-category\/fast-food\/\"><span>Fast Food<\/span><\/a><\/div><div class=\"eltd-ptf-like-holder\"><a class=\"eltd-like\" data-type=\"portfolio_list\" id=\"eltd-like-614-649\" title=\"Like this\"><\/a><\/div>\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n<\/article>\n<article class=\"eltd-portfolio-item mix portfolio_category_70\">\n\n\t\n\t\t<div class = \"eltd-item-image-holder\" >\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/dessert-ideas\/\">\n\t\t\t\t<img width=\"800\" height=\"545\" src=\"https:\/\/demostracionweb.com\/centolo\/wp-content\/uploads\/2016\/04\/port-fi-4-800x545.jpg\" class=\"attachment-savory_elated_landscape size-savory_elated_landscape wp-post-image\" alt=\"f\" loading=\"lazy\" \/>\t\t\t<\/a>\n\n\t\t<\/div>\n\n\t\n\t<div class=\"eltd-item-text-holder\">\n\n\t\t<h4 class=\"eltd-item-title\">\n\n\t\t\t<a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-item\/dessert-ideas\/\">\n\t\t\t\tDessert Ideas\t\t\t<\/a>\n\n\t\t<\/h4>\n\n\t\t\n\t\t\n\t\t\t\t<div class=\"eltd-ptf-category-like-holder clearfix\">\n\t\t\t\t\t<div class=\"eltd-ptf-category-holder\"><a href=\"https:\/\/demostracionweb.com\/centolo\/portfolio-category\/dessert\/\"><span>Dessert<\/span><\/a><\/div><div class=\"eltd-ptf-like-holder\"><a class=\"eltd-like\" data-type=\"portfolio_list\" id=\"eltd-like-612-422\" title=\"Like this\"><\/a><\/div>\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n<\/article>\n<\/div><\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":2343,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":[],"_links":{"self":[{"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/pages\/2331"}],"collection":[{"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/comments?post=2331"}],"version-history":[{"count":0,"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/pages\/2331\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/pages\/2343"}],"wp:attachment":[{"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/media?parent=2331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}