{"id":6522,"date":"2016-10-04T14:50:39","date_gmt":"2016-10-04T14:50:39","guid":{"rendered":"http:\/\/savory.elated-themes.com\/?page_id=6522"},"modified":"2022-10-05T10:48:47","modified_gmt":"2022-10-05T10:48:47","slug":"contacto","status":"publish","type":"page","link":"https:\/\/demostracionweb.com\/centolo\/contacto\/","title":{"rendered":"Contacto"},"content":{"rendered":"<p>[vc_row content_width=\u00bbgrid\u00bb css=\u00bb.vc_custom_1476868419702{padding-top: 93px !important;padding-bottom: 75px !important;}\u00bb][vc_column offset=\u00bbvc_col-lg-offset-0 vc_col-lg-6 vc_col-md-offset-0 vc_col-md-6&#8243; css=\u00bb.vc_custom_1475591753774{padding-right: 5% !important;}\u00bb][vc_empty_space height=\u00bb11px\u00bb]<div class=\"eltd-section-title-outer-holder\" style=\"text-align: left\">\n\n\t\n\t\t\t<div class=\"eltd-section-title-title-holder\">\n\t\t\t\t<h2 class=\"eltd-section-title\" style=\";font-size: 35px;;;;;;\">\n\t\t\t\tContacto\t\t\t\t<\/h2>\n\t\t<\/div>\n\t\n<\/div>[vc_empty_space height=\u00bb10px\u00bb][vc_column_text]\u00bfNos concedes una cita frente al puerto del fin del mundo?[\/vc_column_text][vc_row_inner][vc_column_inner width=\u00bb1\/4&#8243; offset=\u00bbvc_col-lg-3 vc_col-md-3 vc_col-xs-3&#8243;][vc_empty_space height=\u00bb12px\u00bb][vc_column_text]<\/p>\n<h5>Tel\u00e9fono<\/h5>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb4px\u00bb][vc_column_text]<\/p>\n<h5>EMAIL<\/h5>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb4px\u00bb][vc_column_text]<\/p>\n<h5>Direcci\u00f3n<\/h5>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb4px\u00bb][vc_column_text]<\/p>\n<h5>S\u00edguenos<\/h5>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00bb2\/3&#8243; offset=\u00bbvc_col-lg-offset-0 vc_col-lg-9 vc_col-xs-9&#8243;][vc_empty_space height=\u00bb19px\u00bb][vc_column_text]+34 981 740 452[\/vc_column_text][vc_empty_space height=\u00bb7px\u00bb][vc_column_text]<a href=\"mailto:contacto@centolo.com\">contacto@centolo.com<\/a>[\/vc_column_text][vc_empty_space height=\u00bb5px\u00bb][vc_column_text]Avda. del Puerto, s\/n &#8211; 15155 \u2013 Finisterre \u2013 A Coru\u00f1a[\/vc_column_text][vc_empty_space height=\u00bb15px\u00bb]\n    <span class=\"eltd-icon-shortcode normal\" style=\"margin: 0 18px 0 0\" data-hover-color=\"#333333\" data-color=\"#a2a2a2\">\n                    <a class=\"\"  href=\"https:\/\/es-es.facebook.com\/ocentolo\/\" target=\"_blank\">\n        \n        <span aria-hidden=\"true\" class=\"eltd-icon-font-elegant social_facebook eltd-icon-element\" style=\"color: #a2a2a2;font-size:11px\" ><\/span>\n                    <\/a>\n            <\/span>\n\n\n    <span class=\"eltd-icon-shortcode normal\" style=\"margin: 0 18px 0 0\" data-hover-color=\"#333333\" data-color=\"#a2a2a2\">\n                    <a class=\"\"  href=\"https:\/\/www.tripadvisor.co\/Restaurant_Review-g7777650-d2276826-Reviews-O_centolo-Fisterra_Cape_Finisterre_Province_of_A_Coruna_Galicia.html\" target=\"_blank\">\n        \n        <i class=\"eltd-icon-font-awesome fa fa-tripadvisor eltd-icon-element\" style=\"color: #a2a2a2;font-size:11px\" ><\/i>\n                    <\/a>\n            <\/span>\n\n[\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\u00bb30px\u00bb][\/vc_column][vc_column offset=\u00bbvc_col-lg-offset-0 vc_col-lg-6 vc_col-md-offset-0 vc_col-md-6 vc_col-sm-offset-0&#8243;][vc_empty_space height=\u00bb8px\u00bb]<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f175-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/centolo\/wp-json\/wp\/v2\/pages\/6522#wpcf7-f175-o1\" method=\"post\" class=\"wpcf7-form init cf7_custom_style_1\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"175\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.5.5\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f175-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap name\"><input type=\"text\" name=\"name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre*\" \/><\/span><\/p>\n<p><span class=\"wpcf7-form-control-wrap email\"><input type=\"email\" name=\"email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail*\" \/><\/span><\/p>\n<p><span class=\"wpcf7-form-control-wrap message\"><textarea name=\"message\" cols=\"40\" rows=\"5\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Mensaje*\"><\/textarea><\/span><\/p>\n<p><span class=\"wpcf7-form-control-wrap acceptance-310\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-310\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">He le\u00eddo y acepto la pol\u00edtica de privacidad<\/span><\/label><\/span><\/span><\/span><\/p>\n<p><input type=\"submit\" value=\"CONTACTO\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>[vc_empty_space height=\u00bb30px\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d11689.385957190892!2d-9.2627702!3d42.907733!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x0%3A0x4ce2f12b5612368c!2sRestaurante%20O%20Centolo!5e0!3m2!1ses!2ses!4v1645048150916!5m2!1ses!2ses\" width=\"100%\" height=\"450\" allowfullscreen=\"allowfullscreen\"><\/iframe>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row content_width=\u00bbgrid\u00bb css=\u00bb.vc_custom_1476868419702{padding-top: 93px !important;padding-bottom: 75px !important;}\u00bb][vc_column offset=\u00bbvc_col-lg-offset-0 vc_col-lg-6 vc_col-md-offset-0 vc_col-md-6&#8243; css=\u00bb.vc_custom_1475591753774{padding-right: 5% !important;}\u00bb][vc_empty_space height=\u00bb11px\u00bb][vc_empty_space height=\u00bb10px\u00bb][vc_column_text]\u00bfNos concedes una cita frente al puerto del fin del mundo?[\/vc_column_text][vc_row_inner][vc_column_inner width=\u00bb1\/4&#8243; offset=\u00bbvc_col-lg-3 vc_col-md-3 vc_col-xs-3&#8243;][vc_empty_space height=\u00bb12px\u00bb][vc_column_text] Tel\u00e9fono [\/vc_column_text][vc_empty_space height=\u00bb4px\u00bb][vc_column_text] EMAIL [\/vc_column_text][vc_empty_space height=\u00bb4px\u00bb][vc_column_text] Direcci\u00f3n [\/vc_column_text][vc_empty_space height=\u00bb4px\u00bb][vc_column_text] S\u00edguenos [\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00bb2\/3&#8243; offset=\u00bbvc_col-lg-offset-0 vc_col-lg-9&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":[],"_links":{"self":[{"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/pages\/6522"}],"collection":[{"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/comments?post=6522"}],"version-history":[{"count":9,"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/pages\/6522\/revisions"}],"predecessor-version":[{"id":8723,"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/pages\/6522\/revisions\/8723"}],"wp:attachment":[{"href":"https:\/\/demostracionweb.com\/centolo\/wp-json\/wp\/v2\/media?parent=6522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}